{"id":1117,"count":157,"description":"Fokus auf den Schweizer Philanthropie-Sektor. Aktuelle News, gesetzliche Updates und Initiativen, die den nationalen Markt bewegen.","link":"https:\/\/spheriq.ch\/blog\/category\/national\/","name":"National","slug":"national","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>National - Spheriq-Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spheriq.ch\/blog\/category\/national\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"National - Spheriq-Blog\" \/>\n<meta property=\"og:description\" content=\"Fokus auf den Schweizer Philanthropie-Sektor. Aktuelle News, gesetzliche Updates und Initiativen, die den nationalen Markt bewegen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spheriq.ch\/blog\/category\/national\/\" \/>\n<meta property=\"og:site_name\" content=\"Spheriq-Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/spheriq.ch\\\/blog\\\/category\\\/national\\\/\",\"url\":\"https:\\\/\\\/spheriq.ch\\\/blog\\\/category\\\/national\\\/\",\"name\":\"National - Spheriq-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spheriq.ch\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spheriq.ch\\\/blog\\\/category\\\/national\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spheriq.ch\\\/blog\\\/category\\\/national\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spheriq.ch\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"National\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spheriq.ch\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/spheriq.ch\\\/blog\\\/\",\"name\":\"Spheriq-Blog\",\"description\":\"Der Blog f\u00fcr Fundraiser, Stiftungsverwalter, Stiftungsr\u00e4te und alle, die sich f\u00fcr Fragen und Themen rund um den gemeinn\u00fctzigen Sektor interessieren.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spheriq.ch\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"National - Spheriq-Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spheriq.ch\/blog\/category\/national\/","og_locale":"de_DE","og_type":"article","og_title":"National - Spheriq-Blog","og_description":"Fokus auf den Schweizer Philanthropie-Sektor. Aktuelle News, gesetzliche Updates und Initiativen, die den nationalen Markt bewegen.","og_url":"https:\/\/spheriq.ch\/blog\/category\/national\/","og_site_name":"Spheriq-Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/spheriq.ch\/blog\/category\/national\/","url":"https:\/\/spheriq.ch\/blog\/category\/national\/","name":"National - Spheriq-Blog","isPartOf":{"@id":"https:\/\/spheriq.ch\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/spheriq.ch\/blog\/category\/national\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/spheriq.ch\/blog\/category\/national\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spheriq.ch\/blog\/"},{"@type":"ListItem","position":2,"name":"National"}]},{"@type":"WebSite","@id":"https:\/\/spheriq.ch\/blog\/#website","url":"https:\/\/spheriq.ch\/blog\/","name":"Spheriq-Blog","description":"Der Blog f\u00fcr Fundraiser, Stiftungsverwalter, Stiftungsr\u00e4te und alle, die sich f\u00fcr Fragen und Themen rund um den gemeinn\u00fctzigen Sektor interessieren.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spheriq.ch\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/spheriq.ch\/blog\/wp-json\/wp\/v2\/categories\/1117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spheriq.ch\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/spheriq.ch\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/spheriq.ch\/blog\/wp-json\/wp\/v2\/posts?categories=1117"},{"href":"https:\/\/spheriq.ch\/blog\/wp-json\/wp\/v2\/tag_block?categories=1117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}